{"id":1640,"date":"2020-11-29T10:18:51","date_gmt":"2020-11-29T09:18:51","guid":{"rendered":"http:\/\/www.la-petite-vigne.fr\/index.php\/?p=1640"},"modified":"2020-11-29T10:40:23","modified_gmt":"2020-11-29T09:40:23","slug":"message-du-1er-dimanche-de-lavent","status":"publish","type":"post","link":"https:\/\/www.la-petite-vigne.fr\/index.php\/2020\/11\/29\/message-du-1er-dimanche-de-lavent\/","title":{"rendered":"Message du 1er dimanche de l&rsquo;Avent"},"content":{"rendered":"\n<table class=\"wp-block-table\"><tbody><tr><td>Bien chers amis de La Petite Vigne,<br><h3 style=\"color: #ff9900\"><strong><br>En Avent autrement !<\/strong><\/h3><br>Voil\u00e0 comment La Petite Vigne avait choisi d\u2019intituler son traditionnel temps de partage pr\u00e9vu le samedi 5 d\u00e9cembre prochain. Si cette rencontre en pr\u00e9sentiel ne peut avoir lieu, le titre lui, reste plus que jamais d\u2019actualit\u00e9&nbsp;:<br>oui, entrons en Avent\u2026 autrement&nbsp;!&nbsp;<br>Ce temps de l\u2019Avent s\u2019ouvre au c\u0153ur d\u2019une ann\u00e9e particuli\u00e8re et en plein reconfinement. Face aux incertitudes, aux angoisses et \u00e0 la lassitude, la tentation est grande de se recroqueviller sur soi pour attendre des jours meilleurs. Mais la p\u00e9riode de l\u2019Avent nous met en route vers No\u00ebl et l\u2019\u00e9vangile de ce dimanche nous encourage;<\/br><\/br><h3 style=\"color: #ff9900\"><strong>Veillez !<\/strong><\/h3><br>&nbsp;Veiller&nbsp;\u00bb&nbsp;: se lever, s\u2019approcher de la r\u00e9alit\u00e9 pour cr\u00e9er de l\u2019amour v\u00e9ritable avec mes fr\u00e8res et s\u0153urs et avec Dieu.<br>\u00ab&nbsp;Veiller&nbsp;\u00bb&nbsp;:&nbsp;<em>transformer nos paroles et nos actes en outils de paix et de bienveillance<\/em>&nbsp;(Charles Singer&nbsp;<sup>1<\/sup>).<br>\u00ab&nbsp;Veiller&nbsp;\u00bb&nbsp;: marquer notre proximit\u00e9 \u00e0 ceux qui nous entourent. Ceux avec qui nous vivons au quotidien, les membres de notre famille, un ami, une connaissance que l\u2019on sait isol\u00e9e, un voisin, un inconnu crois\u00e9 dans le froid\u2026&nbsp;Qu\u2019attendent-ils de nous&nbsp;? Tout simplement ce que nous attendons nous aussi de l\u2019autre&nbsp;: un regard qui rend vivant,&nbsp;<em>des mots tout droit sortis d\u2019un c\u0153ur avec de la chaleur et plein de douceurs<\/em>&nbsp;<sup>2<\/sup>, une carte, un coup de fil, une oreille attentive\u2026 pour une fois\u2026 Une pri\u00e8re, des mots d\u2019excuses pour apaiser un conflit\u2026Toutes ces richesses qui ne s\u2019ach\u00e8tent pas, que nous poss\u00e9dons tous et que nous pouvons partager&nbsp;!&nbsp;<em>Le bien, comme l\u2019amour \u00e9galement, la justice et la solidarit\u00e9&nbsp;; il faut les conqu\u00e9rir chaque jour<\/em>, nous dit le pape Fran\u00e7ois&nbsp;<sup>3<\/sup>.<\/br><\/br>\n<h3 style=\"color: #ff9900\"><strong>Alors veillons !<\/strong><\/h3>&nbsp;&nbsp;&nbsp;<br>Veillons sur nous-m\u00eame, veillons les uns sur les autres comme l\u2019enfant de la cr\u00e8che veille d\u2019un amour infini sur chaque \u00eatre humain, lui offrant ainsi une dignit\u00e9 infinie.Partageons notre esp\u00e9rance qui d\u00e9tient cet \u00e9trange pouvoir de faire se lever la lumi\u00e8re&nbsp;!<br>Vivons ce temps de l\u2019Avent\u2026 autrement&nbsp;!<br>En Avent toute&nbsp;!&nbsp;<\/br><\/br>Le bureau du CA de la Petite Vigne&nbsp;<\/br><\/br>PS&nbsp;: rendez-vous la semaine prochaine pour le message du deuxi\u00e8me dimanche de l\u2019Avent.<\/br><\/br><sup>1<\/sup>&nbsp;Charles Singer&nbsp;<em>Terres<\/em>&nbsp;p.10<br><sup>2<\/sup>&nbsp;Charles Singer&nbsp;<em>Terres<\/em>&nbsp;p.19<br><sup>3<\/sup>&nbsp;Lettre encyclique&nbsp;<em>Fratelly Tutty<\/em>&nbsp;\u00a711<br><br><\/td><\/tr><\/tbody><\/table>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"591\" height=\"391\" src=\"http:\/\/www.la-petite-vigne.fr\/wp-content\/uploads\/2020\/11\/Avent-2020_1.png\" alt=\"\" class=\"wp-image-1629\" srcset=\"https:\/\/www.la-petite-vigne.fr\/wp-content\/uploads\/2020\/11\/Avent-2020_1.png 591w, https:\/\/www.la-petite-vigne.fr\/wp-content\/uploads\/2020\/11\/Avent-2020_1-300x198.png 300w\" sizes=\"auto, (max-width: 591px) 100vw, 591px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Bien chers amis de La Petite Vigne, En Avent autrement ! Voil\u00e0 comment La Petite Vigne avait choisi d\u2019intituler son traditionnel temps de partage pr\u00e9vu le samedi 5 d\u00e9cembre prochain. Si cette rencontre en pr\u00e9sentiel ne peut avoir lieu, le &hellip; <a href=\"https:\/\/www.la-petite-vigne.fr\/index.php\/2020\/11\/29\/message-du-1er-dimanche-de-lavent\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1640","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.la-petite-vigne.fr\/index.php\/wp-json\/wp\/v2\/posts\/1640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.la-petite-vigne.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.la-petite-vigne.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.la-petite-vigne.fr\/index.php\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.la-petite-vigne.fr\/index.php\/wp-json\/wp\/v2\/comments?post=1640"}],"version-history":[{"count":17,"href":"https:\/\/www.la-petite-vigne.fr\/index.php\/wp-json\/wp\/v2\/posts\/1640\/revisions"}],"predecessor-version":[{"id":1659,"href":"https:\/\/www.la-petite-vigne.fr\/index.php\/wp-json\/wp\/v2\/posts\/1640\/revisions\/1659"}],"wp:attachment":[{"href":"https:\/\/www.la-petite-vigne.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.la-petite-vigne.fr\/index.php\/wp-json\/wp\/v2\/categories?post=1640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.la-petite-vigne.fr\/index.php\/wp-json\/wp\/v2\/tags?post=1640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}